{"id":2663,"date":"2018-06-19T11:03:35","date_gmt":"2018-06-19T09:03:35","guid":{"rendered":"http:\/\/www.kadur.com\/aviso-legal\/"},"modified":"2021-02-18T17:49:38","modified_gmt":"2021-02-18T16:49:38","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/www.kadur.com\/de\/aviso-legal\/","title":{"rendered":"Aviso Legal"},"content":{"rendered":"<p>De acuerdo con la exigencia del art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico (LSSI-CE), DIADUR TOOLS, SL informa de los siguientes datos:<\/p>\n<p><strong>TITULAR WEB<br \/>\n<\/strong>El titular de este sitio web es DIADUR TOOLS, SL, con CIF B58049636, denominaci\u00f3n comercial KADUR y domicilio social en P.I. PLA DE LA BRUGUERA C\/BAGES, 5 de CASTELLAR DEL VALLES, 08211 BARCELONA. La direcci\u00f3n de correo electr\u00f3nico de contacto con la empresa es CONTABILIDAD@KADUR.COM.<\/p>\n<p>DIADUR TOOLS, SL figura inscrita en el Registro Mercantil de BARCELONA, al tomo 23741, folio 43, hoja 57783 y n\u00famero de inscripci\u00f3n 1.<\/p>\n<p>La presente informaci\u00f3n regula las condiciones de uso, las limitaciones de responsabilidad y las obligaciones que los usuarios de la p\u00e1gina Web que se publica bajo el nombre del dominio www.kadur.com las cuales los usuarios asumen y se comprometen a respetar.<\/p>\n<p><strong>OBJETO<\/strong><br \/>\nA trav\u00e9s de este sitio Web, DIADUR TOOLS, SL ofrece servicios de fabricaci\u00f3n de cuchillas industriales buscando satisfacer las necesidades de nuestros usuarios, facilit\u00e1ndoles el acceso a la utilizaci\u00f3n de nuestros servicios y gui\u00e1ndoles en los pasos que debe seguir en la navegaci\u00f3n del mismo.<\/p>\n<p><strong>POL\u00cdTICA DE ENLACES<\/strong><br \/>\nEn caso de que se introduzca por un usuario de Internet un enlace desde su propio Sitio Web al Sitio Web de DIADUR TOOLS, SL, el enlace \u00fanicamente vincular\u00e1 con la p\u00e1gina principal de \u00e9ste \u00faltimo, pero no podr\u00e1 reproducirla de ninguna forma, y, en caso de que se visualicen los contenidos del Sitio Web con contenidos ajenos al mismo, estos contenidos ajenos no podr\u00e1n inducir a error, confusi\u00f3n o enga\u00f1o en los Usuarios sobre la procedencia de sus contenidos, ni suponer un acto de comparaci\u00f3n o imitaci\u00f3n desleal o un aprovechamiento de la reputaci\u00f3n de DIADUR TOOLS, SL.<\/p>\n<p>No se realizar\u00e1 desde la p\u00e1gina que introduce el enlace ning\u00fan tipo de manifestaci\u00f3n falsa o inexacta sobre DIADUR TOOLS, SL, empresas asociadas, colaboradores o empleados, ni se indicar\u00e1 en dicha p\u00e1gina que tienen el consentimiento de DIADUR TOOLS, SL para la inserci\u00f3n del enlace, o que DIADUR TOOLS, SL tiene alguna relaci\u00f3n o colaboraci\u00f3n con dicha p\u00e1gina.<\/p>\n<p>Salvo en los casos permitidos por la ley o expresamente autorizados por DIADUR TOOLS, SL, siempre que se permita un enlace directo con su Sitio Web, queda prohibida la utilizaci\u00f3n de cualquier marca o cualquier otro signo distintivo de KADUR dentro de la p\u00e1gina donde se encuentre el enlace, salvo que se autorice expresamente.<\/p>\n<p>La p\u00e1gina que establezca el enlace deber\u00e1 cumplir con la ley y no disponer o enlazar con contenidos il\u00edcitos o contrarios a la moral y a las buenas costumbres.<\/p>\n<p>Por su parte, el propio Sitio Web incluye dispositivos t\u00e9cnicos de enlace que permiten al Usuario acceder a otras p\u00e1ginas y portales de Internet, actuando DIADUR TOOLS, SL como prestador de servicios de intermediaci\u00f3n de conformidad con el art\u00edculo 17 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico, por lo que s\u00f3lo ser\u00e1 responsable de los contenidos y servicios suministrados en los sitios enlazados en caso que habiendo tenido conocimiento efectivo, en la forma prevista por la Ley de Servicios de la Sociedad de la Informaci\u00f3n, de la ilicitud no haya desactivado el enlace.<\/p>\n<p>La existencia de sitios enlazados no supone que existan acuerdos con los responsables o titulares de los mismos, y DIADUR TOOLS, SL no se hace responsable por los da\u00f1os producidos por la ilicitud, calidad, desactualizaci\u00f3n, indisponibilidad, error e inutilidad de los contenidos de dichos sitios, puesto que los desconoce. En cualquier caso, si el Usuario tuviera conocimiento de que los sitios enlazados remiten a p\u00e1ginas cuyos contenidos o servicios son il\u00edcitos o contrarios a la moral deber\u00e1 ponerlo en conocimiento de DIADUR TOOLS, SL.<\/p>\n<p>A estos efectos se habilita la direcci\u00f3n de correo electr\u00f3nico CONTABILIDAD@KADUR.COM, de esta forma, los usuarios deber\u00e1n comunicar: nombre, direcci\u00f3n, n\u00famero de tel\u00e9fono y direcci\u00f3n de correo electr\u00f3nico; especificaci\u00f3n de la supuesta actividad il\u00edcita llevada a cabo en el Portal; hechos o circunstancias que revelan el car\u00e1cter il\u00edcito de dicha actividad.<\/p>\n<p><strong>CONDICIONES DE USO<\/strong><br \/>\nLa utilizaci\u00f3n de la p\u00e1gina otorga la utilizaci\u00f3n de usuario e implica la aceptaci\u00f3n de las condiciones del aviso legal, pol\u00edtica de privacidad y condiciones de uso, si el usuario no estuviera conforme, se abstendr\u00e1 de utilizar la p\u00e1gina. El usuario est\u00e1 obligado y se compromete a utilizar la p\u00e1gina y los contenidos de conformidad con la legislaci\u00f3n vigente, el Aviso Legal, y cualquier otro aviso contenido en esta p\u00e1gina, as\u00ed como con las normas de convivencia, la moral y buenas costumbres generalmente aceptadas.<\/p>\n<p>El Usuario se obliga y se compromete a no transmitir, difundir o poner a disposici\u00f3n de terceros cualquier contenido de la P\u00e1gina, tales como informaciones, textos, datos, contenidos, mensajes, gr\u00e1ficos, dibujos, archivos de sonido y\/o imagen, fotograf\u00edas, grabaciones, software, logotipos, marcas, iconos, tecnolog\u00eda, fotograf\u00edas, software, enlaces, dise\u00f1o gr\u00e1fico y c\u00f3digos fuente, o cualquier otro material al que tuviera acceso en su condici\u00f3n de Usuario de la P\u00e1gina, sin que esta enumeraci\u00f3n tenga car\u00e1cter limitativo.<\/p>\n<p><strong>PROPIEDAD INTELECTUAL E INDUSTRIAL<\/strong><br \/>\nTodas las marcas, nombres comerciales o signos distintivos de cualquier clase que aparecen en la p\u00e1gina son propiedad de DIADUR TOOLS, SL o, en su caso, de terceros que han autorizado su uso, sin que pueda entenderse que el uso o acceso al portal y\/o a los contenidos atribuya al usuario derecho alguno sobre las citadas marcas, nombres comerciales y\/o signos distintivos, y sin que puedan entenderse cedidos al usuario, ninguno de los derechos de explotaci\u00f3n que existen o puedan existir sobre dichos contenidos. Y no entiende cedidos ni se autoriza su utilizaci\u00f3n, en ning\u00fan caso, a los usuarios de la p\u00e1gina salvo que se obtengan dichos derechos por escrito del leg\u00edtimo titular de los mismos.<\/p>\n<p><strong>REDES SOCIALES OFICIALES<\/strong><br \/>\nEl prestador de servicios de las p\u00e1ginas oficiales de KADUR en redes sociales es la entidad DIADUR TOOLS, SL con CIF B58049636 y domicilio social en P.I. PLA DE LA BRUGUERA C\/BAGES, 5 de CASTELLAR DEL VALLES, 08211 BARCELONA y mismo domicilio a efecto de notificaciones.<br \/>\nEl acceso y uso de estas p\u00e1ginas requiere de la aceptaci\u00f3n de las condiciones generales de uso de redes sociales y la pol\u00edtica de privacidad que m\u00e1s abajo se detalla y se completa con la pol\u00edtica y las normas de las plataformas de cada red social.<br \/>\nPara cualquier consulta o contacto con DIADUR TOOLS, SL los usuarios podr\u00e1n comunicarse a trav\u00e9s del n\u00famero de tel\u00e9fono 937142522 o de la siguiente direcci\u00f3n electr\u00f3nica: CONTABILIDAD@KADUR.COM.<br \/>\nCondiciones de uso de la p\u00e1gina oficial de KADUR en redes sociales<br \/>\nPor favor, lea atentamente estas condiciones de uso ya que contienen toda la informaci\u00f3n relativa a sus derechos y obligaciones como usuario de la p\u00e1gina oficial de KADUR en redes sociales. El acceso y uso de la p\u00e1gina oficial de KADUR en redes sociales est\u00e1 sujeto adem\u00e1s al cumplimiento de las condiciones establecidas por cada red social como titular de la plataforma del servicio de red social.<\/p>\n<p>Facebook: <a href=\"https:\/\/www.facebook.com\/help\/323540651073243\/\">https:\/\/www.facebook.com\/help\/323540651073243\/<\/a><br \/>\nTwitter: https:\/\/twitter.com\/privacy<br \/>\nInstagram: http:\/\/instagram.com\/about\/legal\/privacy\/<br \/>\nLinkedin: http:\/\/www.linkedin.com\/legal\/privacy-policy?trk=hb_ft_priv<br \/>\nGoogle +: http:\/\/www.google.com\/intl\/es\/policies\/privacy\/<\/p>\n<p>Cuando el usuario accede o utiliza la p\u00e1gina oficial de KADUR en redes sociales manifiesta su consentimiento y aceptaci\u00f3n del cumplimiento de lo establecido en las presentes condiciones de uso.<br \/>\nEl acceso y uso de la p\u00e1gina oficial de KADUR en redes sociales est\u00e1 prohibido a los menores de 14 a\u00f1os.<\/p>\n<p><strong>Usos permitidos y usos prohibidos<\/strong><br \/>\nA trav\u00e9s de la p\u00e1gina oficial de KADUR en redes sociales se facilita un espacio en el que el usuario puede publicar e intercambiar informaci\u00f3n y contenidos, as\u00ed como establecer comunicaci\u00f3n entre varios usuarios.<br \/>\nEl uso de la p\u00e1gina oficial de KADUR no puede tener una finalidad econ\u00f3mica o comercial.<\/p>\n<p>El usuario est\u00e1 obligado a realizar un uso razonable de la p\u00e1gina oficial de KADUR de las redes sociales y de sus contenidos, seg\u00fan las posibilidades y fines para los que est\u00e1 concebido de acuerdo con los usos y costumbres, la moral, la legislaci\u00f3n vigente, las presentes normas y las normas y pol\u00edticas publicadas por las redes sociales. El usuario ser\u00e1 el \u00fanico responsable de la informaci\u00f3n, im\u00e1genes, opiniones, alusiones o contenidos de cualquier tipo que comunique, aloje, transmita, ponga a disposici\u00f3n o exhiba a trav\u00e9s de la p\u00e1gina oficial de KADUR en redes sociales.<\/p>\n<p>DIADUR TOOLS, SL no podr\u00e1 ser considerado responsable editorial de los contenidos publicados por el usuario y declara expresamente que no se identifica con ninguna de las opiniones que los usuarios publiquen en la p\u00e1gina oficial de KADUR en redes sociales de cuyas consecuencias se hace enteramente responsable el emisor de las mismas.<\/p>\n<p>En todo caso, queda prohibido el uso de la p\u00e1gina oficial de KADUR en redes sociales con fines ilegales o no autorizados, con o sin finalidad econ\u00f3mica.<\/p>\n<p><strong>EXENCI\u00d3N DE RESPONSABILIDADES<\/strong><br \/>\nDIADUR TOOLS, SL incluye en su Sitio Web una serie de contenidos sobre sus actividades, productos, estructura, gesti\u00f3n y equipos propios de una Web corporativa. DIADUR TOOLS, SL excluye cualquier responsabilidad por los da\u00f1os y perjuicios de toda naturaleza que pudieran derivarse del acceso a los contenidos, informaciones, publicidad, opciones, conceptos e im\u00e1genes facilitados a los usuarios.<br \/>\nEn cualquier caso, DIADUR TOOLS, SL no se hace responsable de:<\/p>\n<ul>\n<li>El mal que el usuario pueda realizar del Sitio Web.<\/li>\n<li>La continuidad de los contenidos de la Sitio Web.<\/li>\n<li>La ausencia de virus y\/o dem\u00e1s componentes da\u00f1inos en el Sitio Web o en el servidor que los suministra, tanto en lo relativo a la visualizaci\u00f3n de los contenidos por los usuarios como en la descarga de los mismos.<\/li>\n<li>Los contenidos y servicios prestados por otros Sitios Web a las que pueda tener acceso desde las direcciones de Internet titularidad de DIADUR TOOLS, SL.<\/li>\n<li>El mayor o menor rendimiento de los contenidos albergados en el Sitio Web.<\/li>\n<li>Los da\u00f1os o perjuicios que causare cualquier persona, bien a si misma o a terceras, que infringiera las condiciones, normas e instrucciones que DIADUR TOOLS, SL en este Sitio Web.<\/li>\n<li>Los da\u00f1os ocasionados por la vulneraci\u00f3n de los sistemas de seguridad del Sitio Web titularidad de DIADUR TOOLS, SL.<\/li>\n<li>El mal funcionamiento de software o plug-ins (descarga que pudiere realizarse desde el link establecido al efecto), que pudiera ser necesario para la visualizaci\u00f3n o escucha de determinados contenidos albergados en el presente Sitio Web.<\/li>\n<li>Cualquier acci\u00f3n o actuaci\u00f3n que pudiere realizar en relaci\u00f3n con la vulneraci\u00f3n de derechos de terceros, especialmente, con relaci\u00f3n a la imagen, propiedad intelectual o industrial.<br \/>\nDe la edici\u00f3n, revisi\u00f3n, censura y verificaci\u00f3n de los contenidos de las p\u00e1ginas o Sitios de Internet con los que el usuario se conecte a trav\u00e9s del motor de b\u00fasqueda o de hiperv\u00ednculos incluidos en el Sitio Web de DIADUR TOOLS, SL.<\/li>\n<\/ul>\n<p>Exenci\u00f3n de responsabilidad por el funcionamiento de la P\u00e1gina Web<br \/>\nDIADUR TOOLS, SL presta sus servicios y contenidos de forma continuada empleando todos los medios t\u00e9cnicos a su alcance para realizar dicha prestaci\u00f3n de forma satisfactoria.<\/p>\n<p>DIADUR TOOLS, SL podr\u00e1, cuando lo considere conveniente, realizar correcciones, mejoras o modificaciones en la informaci\u00f3n contenida en su Sitio Web, sin que ello de lugar, ni derecho a ninguna reclamaci\u00f3n o indemnizaci\u00f3n, ni implique reconocimiento de responsabilidad alguna.<\/p>\n<p>DIADUR TOOLS, SL no se hacer responsable por los da\u00f1os y perjuicios de toda naturaleza que pudieran derivarse de la disponibilidad y continuidad t\u00e9cnica del funcionamiento de su Sitio Web. En cualquier caso, DIADUR TOOLS, SL llevar\u00e1 a cabo todas las actuaciones necesarias para restablecer sus servicios en caso de fallo t\u00e9cnico.<\/p>\n<p><strong>LEGISLACI\u00d3N Y JURISDICCI\u00d3N<\/strong><br \/>\nDIADUR TOOLS, SL se reserva la facultad de presentar las acciones civiles o penales que considere oportunas por la utilizaci\u00f3n indebida de su sitio web y contenidos, o por el incumplimiento de las presentes condiciones.<br \/>\nEn caso de existir discrepancia entre lo establecido en el presente Aviso Legal y las Condiciones Particulares de cada servicio espec\u00edfico, prevalecer\u00e1 lo dispuesto en \u00e9stas \u00faltimas.<\/p>\n<p>En el caso de que cualquier disposici\u00f3n o disposiciones contenidas en el presente Aviso Legal fueran consideradas nulas o inaplicables, en su totalidad o en parte, por cualquier Juzgado, Tribunal u \u00f3rgano administrativo competente, dicha nulidad o inaplicaci\u00f3n no afectar\u00e1 al resto de disposiciones del presente Aviso Legal ni a las Condiciones Particulares de los diferentes servicios del presente Sitio Web.<\/p>\n<p>El no ejercicio o ejecuci\u00f3n, por parte de DIADUR TOOLS, SL de cualquier derecho o disposici\u00f3n contenido en estas Condiciones Generales no constituir\u00e1 una renuncia al mismo, salvo reconocimiento y acuerdo escrito por su parte.<\/p>\n<p>La relaci\u00f3n entre el usuario y el prestador se regir\u00e1 por la normativa vigente y de aplicaci\u00f3n en el territorio espa\u00f1ol. De surgir cualquier controversia las partes podr\u00e1n someter sus conflictos a arbitraje o acudir a la jurisdicci\u00f3n ordinaria cumpliendo con las normas sobre jurisdicci\u00f3n y competencia al respecto. DIADUR TOOLS, SL tiene su domicilio en CASTELLAR DEL VALLES, Espa\u00f1a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acuerdo con la exigencia del art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico (LSSI-CE), DIADUR TOOLS, SL informa de los siguientes datos: TITULAR WEB El &hellip; <br \/><a href=\"https:\/\/www.kadur.com\/de\/aviso-legal\/\" class=\"more-link\">Lesen Sie weiter<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aviso Legal - Kadur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kadur.com\/de\/aviso-legal\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aviso Legal - Kadur\" \/>\n<meta property=\"og:description\" content=\"De acuerdo con la exigencia del art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico (LSSI-CE), DIADUR TOOLS, SL informa de los siguientes datos: TITULAR WEB El &hellip; Lesen Sie weiter\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kadur.com\/de\/aviso-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"Kadur\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-18T16:49:38+00:00\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"12\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.kadur.com\/de\/aviso-legal\/\",\"url\":\"https:\/\/www.kadur.com\/de\/aviso-legal\/\",\"name\":\"Aviso Legal - Kadur\",\"isPartOf\":{\"@id\":\"https:\/\/www.kadur.com\/fr\/#website\"},\"datePublished\":\"2018-06-19T09:03:35+00:00\",\"dateModified\":\"2021-02-18T16:49:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.kadur.com\/de\/aviso-legal\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.kadur.com\/de\/aviso-legal\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.kadur.com\/de\/aviso-legal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.kadur.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aviso Legal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.kadur.com\/fr\/#website\",\"url\":\"https:\/\/www.kadur.com\/fr\/\",\"name\":\"Kadur\",\"description\":\"Industrielle Hochleistungs-Messer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.kadur.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aviso Legal - Kadur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kadur.com\/de\/aviso-legal\/","og_locale":"de_DE","og_type":"article","og_title":"Aviso Legal - Kadur","og_description":"De acuerdo con la exigencia del art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico (LSSI-CE), DIADUR TOOLS, SL informa de los siguientes datos: TITULAR WEB El &hellip; Lesen Sie weiter","og_url":"https:\/\/www.kadur.com\/de\/aviso-legal\/","og_site_name":"Kadur","article_modified_time":"2021-02-18T16:49:38+00:00","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"12\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kadur.com\/de\/aviso-legal\/","url":"https:\/\/www.kadur.com\/de\/aviso-legal\/","name":"Aviso Legal - Kadur","isPartOf":{"@id":"https:\/\/www.kadur.com\/fr\/#website"},"datePublished":"2018-06-19T09:03:35+00:00","dateModified":"2021-02-18T16:49:38+00:00","breadcrumb":{"@id":"https:\/\/www.kadur.com\/de\/aviso-legal\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kadur.com\/de\/aviso-legal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kadur.com\/de\/aviso-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kadur.com\/de\/"},{"@type":"ListItem","position":2,"name":"Aviso Legal"}]},{"@type":"WebSite","@id":"https:\/\/www.kadur.com\/fr\/#website","url":"https:\/\/www.kadur.com\/fr\/","name":"Kadur","description":"Industrielle Hochleistungs-Messer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kadur.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.kadur.com\/de\/wp-json\/wp\/v2\/pages\/2663"}],"collection":[{"href":"https:\/\/www.kadur.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.kadur.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.kadur.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kadur.com\/de\/wp-json\/wp\/v2\/comments?post=2663"}],"version-history":[{"count":0,"href":"https:\/\/www.kadur.com\/de\/wp-json\/wp\/v2\/pages\/2663\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kadur.com\/de\/wp-json\/wp\/v2\/media?parent=2663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}